{"id":2774,"date":"2022-08-29T09:49:59","date_gmt":"2022-08-29T09:49:59","guid":{"rendered":"https:\/\/capsenegal.com\/?p=2774"},"modified":"2022-11-16T12:17:43","modified_gmt":"2022-11-16T12:17:43","slug":"__trashed","status":"publish","type":"post","link":"https:\/\/capsenegal.com\/en\/__trashed\/","title":{"rendered":"TOURNOI CAP SENEGAL"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Les quarts de finale du tournoi de Cap S\u00e9n\u00e9gal ont d\u00e9but\u00e9 ce samedi 27 Ao\u00fbt 2022 au stade DEGGO des Maristes. Deux matchs \u00e9taient \u00e0 l&rsquo;affiche: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>ICS vs FT2: <strong><em>victoire ICS 2 buts \u00e0 1<\/em><\/strong> ; buteurs : Dame B\u00e8ye (10) et Ibrahima Mbodji (14) pour ICS contre Mouhamed Fall (8) pour FT2<\/li>\n\n\n\n<li>MLT sa vs DOUANES : 2 buts partout ; buteurs : Idrissa Samb et El Hadji Diame S\u00e8ne pour MLT et Ibra  Diop et Mouhamed Diouf pour la Douane. <\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><em style=\"\"><mark style=\"background-color: rgba(0, 0, 0, 0);\" class=\"has-inline-color has-pale-pink-color\"><b>TIRS AU BU<\/b><\/mark><\/em><strong><em><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-pale-pink-color\">T : victoire DOUANE par 3 \u00e0 2<\/mark><\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> <\/p>","protected":false},"excerpt":{"rendered":"<p>Les quarts de finale du tournoi de Cap S\u00e9n\u00e9gal ont d\u00e9but\u00e9 ce samedi 27 Ao\u00fbt 2022 au stade DEGGO des Maristes. Deux matchs \u00e9taient \u00e0 l&rsquo;affiche: TIRS AU BUT : victoire DOUANE par 3 \u00e0 2<\/p>","protected":false},"author":69,"featured_media":2456,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"acf":[],"_links":{"self":[{"href":"https:\/\/capsenegal.com\/en\/wp-json\/wp\/v2\/posts\/2774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/capsenegal.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/capsenegal.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/capsenegal.com\/en\/wp-json\/wp\/v2\/users\/69"}],"replies":[{"embeddable":true,"href":"https:\/\/capsenegal.com\/en\/wp-json\/wp\/v2\/comments?post=2774"}],"version-history":[{"count":3,"href":"https:\/\/capsenegal.com\/en\/wp-json\/wp\/v2\/posts\/2774\/revisions"}],"predecessor-version":[{"id":2793,"href":"https:\/\/capsenegal.com\/en\/wp-json\/wp\/v2\/posts\/2774\/revisions\/2793"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/capsenegal.com\/en\/wp-json\/wp\/v2\/media\/2456"}],"wp:attachment":[{"href":"https:\/\/capsenegal.com\/en\/wp-json\/wp\/v2\/media?parent=2774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/capsenegal.com\/en\/wp-json\/wp\/v2\/categories?post=2774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/capsenegal.com\/en\/wp-json\/wp\/v2\/tags?post=2774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}